{"id":389,"count":1,"description":"","link":"https:\/\/www.galvanizers.co.in\/blog\/tag\/tanyagalvanizers\/","name":"tanyagalvanizers","slug":"tanyagalvanizers","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>tanyagalvanizers Archives | Galvanizers<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"tanyagalvanizers Archives | Galvanizers\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.galvanizers.co.in\/blog\/tag\/tanyagalvanizers\/\" \/>\n<meta property=\"og:site_name\" content=\"Galvanizers\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.galvanizers.co.in\/blog\/wp-content\/uploads\/2023\/08\/Galvanizer-Logo.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"250\" \/>\n\t<meta property=\"og:image:height\" content=\"250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@galvanizerindia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.galvanizers.co.in\\\/blog\\\/tag\\\/tanyagalvanizers\\\/\",\"url\":\"https:\\\/\\\/www.galvanizers.co.in\\\/blog\\\/tag\\\/tanyagalvanizers\\\/\",\"name\":\"tanyagalvanizers Archives | Galvanizers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.galvanizers.co.in\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.galvanizers.co.in\\\/blog\\\/tag\\\/tanyagalvanizers\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.galvanizers.co.in\\\/blog\\\/tag\\\/tanyagalvanizers\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.galvanizers.co.in\\\/blog\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"tanyagalvanizers\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.galvanizers.co.in\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/www.galvanizers.co.in\\\/blog\\\/\",\"name\":\"Galvanizers\",\"description\":\"Supplier &amp; Consultant of Hot Dip Galvanizing Plants in India.\",\"alternateName\":\"Tanya Galvanizers\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.galvanizers.co.in\\\/blog\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"tanyagalvanizers Archives | Galvanizers","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_US","og_type":"article","og_title":"tanyagalvanizers Archives | Galvanizers","og_url":"https:\/\/www.galvanizers.co.in\/blog\/tag\/tanyagalvanizers\/","og_site_name":"Galvanizers","og_image":[{"width":250,"height":250,"url":"https:\/\/www.galvanizers.co.in\/blog\/wp-content\/uploads\/2023\/08\/Galvanizer-Logo.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@galvanizerindia","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.galvanizers.co.in\/blog\/tag\/tanyagalvanizers\/","url":"https:\/\/www.galvanizers.co.in\/blog\/tag\/tanyagalvanizers\/","name":"tanyagalvanizers Archives | Galvanizers","isPartOf":{"@id":"https:\/\/www.galvanizers.co.in\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/www.galvanizers.co.in\/blog\/tag\/tanyagalvanizers\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.galvanizers.co.in\/blog\/tag\/tanyagalvanizers\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.galvanizers.co.in\/blog\/"},{"@type":"ListItem","position":2,"name":"tanyagalvanizers"}]},{"@type":"WebSite","@id":"https:\/\/www.galvanizers.co.in\/blog\/#website","url":"https:\/\/www.galvanizers.co.in\/blog\/","name":"Galvanizers","description":"Supplier &amp; Consultant of Hot Dip Galvanizing Plants in India.","alternateName":"Tanya Galvanizers","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.galvanizers.co.in\/blog\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.galvanizers.co.in\/blog\/wp-json\/wp\/v2\/tags\/389","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.galvanizers.co.in\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.galvanizers.co.in\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.galvanizers.co.in\/blog\/wp-json\/wp\/v2\/posts?tags=389"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}